{"id":6989,"date":"2026-05-27T10:38:35","date_gmt":"2026-05-27T08:38:35","guid":{"rendered":"https:\/\/chs-containergroup.com\/de\/agb\/widerrufsbelehrung-fuer-verbraucher\/"},"modified":"2026-05-27T10:54:07","modified_gmt":"2026-05-27T08:54:07","slug":"widerrufsbelehrung-fuer-verbraucher","status":"publish","type":"page","link":"https:\/\/chs-containergroup.com\/de\/agb\/widerrufsbelehrung-fuer-verbraucher\/","title":{"rendered":"Widerrufsbelehrung fu\u0308r Verbraucher"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Widerrufsrecht<\/h2>\n\n<p class=\"wp-block-paragraph\">Sie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen. Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die Ware (oder die letzte Ware, Teilsendung oder St\u00fcck im Falle eines Vertrags \u00fcber mehrere Waren einer einheitlichen Bestellung oder die Lieferung einer Ware in mehreren Teilsendungen oder St\u00fccken) in Besitz genommen haben bzw. hat.<\/p>\n\n<p class=\"wp-block-paragraph\">Um Ihr Widerrufsrecht auszu\u00fcben, f\u00fcllen Sie bitte <strong>das Widerrufsformular am Ende dieser Seite<\/strong> aus.Um Ihr Widerrufsrecht auszu\u00fcben, f\u00fcllen Sie bitte das Widerrufsformular am Ende dieser Seite aus. Alternativ k\u00f6nnen Sie uns (CHS Container Handel GmbH, Tillmannstr. 19, 28239 Bremen) durch eine eindeutige Erkl\u00e4rung (z. B. ein per Post versandter Brief oder eine E-Mail) \u00fcber Ihren Entschluss, diesen Vertrag zu widerrufen, informieren. Sie k\u00f6nnen daf\u00fcr das auf unserer Website verf\u00fcgbare Muster-Widerrufsformular verwenden, dies ist jedoch nicht vorgeschrieben.  <\/p>\n\n<p class=\"wp-block-paragraph\">Zur Wahrung der Widerrufsfrist reicht es aus, dass Sie die Mitteilung \u00fcber die Aus\u00fcbung des Widerrufsrechts vor Ablauf der Widerrufsfrist absenden.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Hinweis:<\/strong><br\/>Bei Vertr\u00e4gen \u00fcber die Lieferung von Waren, die nicht vorgefertigt sind und f\u00fcr deren Herstellung<br\/>eine individuelle Auswahl oder Bestimmung durch den Verbraucher ma\u00dfgeblich ist oder die eindeutig<br\/>auf die pers\u00f6nlichen Bed\u00fcrfnisse des Verbrauchers zugeschnitten sind, steht Ihnen kein Widerrufsrecht zu (vgl. \u00a7 312g Abs. 2 Nr. 1 BGB)<\/p>\n\n<p class=\"wp-block-paragraph\">Dies betrifft insbesondere Container, die auf ausdr\u00fccklichen Kundenwunsch hin in Bezug auf Ausstattung, Ma\u00dfe, Farbe, Innenausbau oder sonstige Spezifikationen angefertigt werden.<\/p>\n\n<h2 class=\"wp-block-heading\">Folgen des Widerrufs<\/h2>\n\n<p class=\"wp-block-paragraph\">Wenn Sie diesen Vertrag widerrufen, haben wir Ihnen alle Zahlungen, die wir von Ihnen erhalten haben, einschlie\u00dflich der Lieferkosten (mit Ausnahme der zus\u00e4tzlichen Kosten, die sich daraus ergeben, dass Sie eine andere Art der Lieferung als die von uns angebotene, g\u00fcnstigste Standardlieferung gew\u00e4hlt haben), unverz\u00fcglich und sp\u00e4testens binnen vierzehn Tagen ab dem Tag zur\u00fcckzuzahlen, an dem die Mitteilung \u00fcber Ihren Widerruf dieses Vertrags bei uns eingegangen ist. F\u00fcr diese R\u00fcckzahlung verwenden wir dasselbe Zahlungsmittel, das Sie bei der urspr\u00fcnglichen Transaktion eingesetzt haben, es sei denn, mit Ihnen wurde ausdr\u00fccklich etwas anderes vereinbart; in keinem Fall werden Ihnen wegen dieser R\u00fcckzahlung Entgelte berechnet. Wir k\u00f6nnen die R\u00fcckzahlung verweigern, bis wir die Waren wieder zur\u00fcckerhalten haben oder bis Sie den Nachweis erbracht haben, dass Sie die Waren zur\u00fcckgesandt haben, je nachdem, welches der fr\u00fchere Zeitpunkt ist.  <\/p>\n\n<p class=\"wp-block-paragraph\">Sie haben die Waren unverz\u00fcglich und in jedem Fall sp\u00e4testens binnen vierzehn Tagen ab dem Tag, an dem Sie uns \u00fcber den Widerruf dieses Vertrags unterrichten, an uns zur\u00fcckzusenden. Die Frist ist gewahrt, wenn Sie die Waren vor Ablauf der Frist von vierzehn Tagen fachgerecht absenden. Bez\u00fcglich der R\u00fccksendung ist zudem folgendes zu beachten:  <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Aufgrund der Beschaffenheit der Ware kann die R\u00fccksendung \u00fcblicherweise nur per Spedition erfolgen.<\/li>\n\n\n\n<li>Die unmittelbaren Kosten der R\u00fccksendung der Waren haben Sie zu tragen. Die Kosten entsprechen<br\/>\u00fcblicherweise den urspr\u00fcnglichen Lieferkosten. <\/li>\n\n\n\n<li>Sie m\u00fcssen f\u00fcr einen etwaigen Wertverlust der Waren nur aufkommen, wenn dieser Wertverlust auf<br\/>einen zur Pr\u00fcfung der Beschaffenheit, Eigenschaften und Funktionsweise der Waren nicht notwendigen Umgang mit ihnen zur\u00fcckzuf\u00fchren ist.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">Widerrufsformular<\/h3>\n\n<p class=\"wp-block-paragraph\"><strong>Hinweis:<\/strong> Wenn Sie den Vertrag widerrufen wollen, dann f\u00fcllen Sie bitte dieses Formular aus, streichen Sie die unzutreffenden Angaben und senden Sie es zur\u00fcck.<\/p>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f6990-o1\" lang=\"de-DE\" dir=\"ltr\" data-wpcf7-id=\"6990\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/6989#wpcf7-f6990-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"6990\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f6990-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"EXIT_PAGE_URL\" value=\"https:\/\/chs-containergroup.com\/de\/wp-json\/wp\/v2\/pages\/6989\" \/>\n<\/fieldset>\n<p>Hiermit widerrufe(n) ich\/wir den von mir\/uns abgeschlossenen Vertrag \u00fcber den Kauf mit der folgenden Bestellnummer und Kaufdetails:\n<\/p>\n<p><label style=\"padding-top:20px\" for=\"order-number\">Bestell-,Auftrags- oder Rechnungsnummer*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"order-number\"><input size=\"40\" maxlength=\"20\" minlength=\"3\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"order-number\" \/><\/span>\n<\/p>\n<p><label style=\"padding-top:20px\" for=\"input-full-name\">Name*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"full-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" id=\"input-full-name\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"full-name\" \/><\/span>\n<\/p>\n<p><label style=\"padding-top:20px\" for=\"input-street\">Stra\u00dfe \/ Hausnummer *<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"street\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" id=\"input-street\" autocomplete=\"street-address\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"street\" \/><\/span>\n<\/p>\n<p><label style=\"padding-top:20px\" for=\"input-city\">Postleitzahl \/ Stadt*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"city\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" id=\"input-city\" autocomplete=\"postal-code\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"city\" \/><\/span>\n<\/p>\n<p><label style=\"padding-top:20px\" for=\"input-phone\">Telefon*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel form-control\" id=\"input-phone\" autocomplete=\"tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"phone\" \/><\/span>\n<\/p>\n<div style=\"padding-bottom:20px;\">\n\t<p><label style=\"padding-top:20px;\" for=\"input-email\">E-Mail*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email form-control\" id=\"input-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t<\/p>\n<\/div>\n<p>*Pflichtfelder\n<\/p>\n<div style=\"padding-top:20px;\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"data-processing\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"data-processing\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Ich habe die Informationen zur <a href=\"https:\/\/chs-containergroup.com\/de\/datenschutz\/\" target=\"_blank\">Datenverarbeitung gelesen und verstanden .<\/a> Meine Angaben werden von der CHS Container Holding GmbH unter Beachtung der vorstehenden Datenschutzhinweise zum Zwecke der Angebotserstellung und der Bearbeitung meiner Anfrage verarbeitet.*<\/span><\/label><\/span><\/span><\/span>\n\t<\/p>\n<\/div>\n<p><span id=\"wpcf7-6a571752b62f6-wrapper\" class=\"wpcf7-form-control-wrap honeypot-1-wrap\" style=\"display: block;\n\t\t    width: 0px;\n\t\t    height: 0px;\n\t\t    padding: 0px;\n\t\t    border: 1px solid transparent;\n\t\t    display: block;\n\t\t    overflow: hidden;\n\t\t    \"><input type=\"hidden\" name=\"honeypot-1-random-hash\" value=\"50035766\"><label\n\t\t    for=\"wpcf7-6a571752b62f6-field\"\n\t\t    class=\"hp-message\"\n        >Bitte lasse dieses Feld leer.<\/label><input\n\t    id=\"wpcf7-6a571752b62f6-field\"\n\t    \n\t    class=\"wpcf7-form-control wpcf7-text\"\n\t    type=\"text\"\n\t    name=\"npm4kijkdavn\"\n\t    value=\"\"\n\t    size=\"40\"\n\t    autocomplete=\"new-password\"\n\t    tabindex=\"1000\"\n    \/><\/span>\n<\/p>\n<p class=\"submit-btn-wrapper\" style=\"padding-top: 20px\"><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-primary\" type=\"submit\" value=\"WIDERRUF BEST\u00c4TIGEN\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Widerrufsrecht Sie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen. Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die Ware (oder die letzte Ware, Teilsendung oder St\u00fcck im Falle eines Vertrags \u00fcber mehrere Waren einer [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":319,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-6989","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/chs-containergroup.com\/de\/wp-json\/wp\/v2\/pages\/6989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chs-containergroup.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/chs-containergroup.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/chs-containergroup.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/chs-containergroup.com\/de\/wp-json\/wp\/v2\/comments?post=6989"}],"version-history":[{"count":0,"href":"https:\/\/chs-containergroup.com\/de\/wp-json\/wp\/v2\/pages\/6989\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/chs-containergroup.com\/de\/wp-json\/wp\/v2\/pages\/319"}],"wp:attachment":[{"href":"https:\/\/chs-containergroup.com\/de\/wp-json\/wp\/v2\/media?parent=6989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}